{"id":3367,"date":"2022-09-27T15:47:00","date_gmt":"2022-09-27T13:47:00","guid":{"rendered":"https:\/\/naranjasamparo.net\/blog\/?p=3367"},"modified":"2022-09-18T15:57:19","modified_gmt":"2022-09-18T13:57:19","slug":"regadio-de-los-citricos-sistemas","status":"publish","type":"post","link":"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/","title":{"rendered":"Regad\u00edo de los c\u00edtricos: Sistemas"},"content":{"rendered":"\n<p><strong>\u00bfCu\u00e1l es el origen del regad\u00edo de los c\u00edtricos de los campos valencianos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\">Las acequias, han constituido durante muchos a\u00f1os un papel fundamental en el regad\u00edo de los <a href=\"http:\/\/naranjasamparo.net\"><strong>c\u00edtricos<\/strong><\/a>. Las acequias son canales o conductos por donde se conducen las aguas para regar campos de cultivo, como pueden ser los campos de c\u00edtricos.<br>Estas obras son conductos largos y estrechos construidas generalmente a cielo abierto. Tienen como funci\u00f3n recoger el agua de lugares de captaci\u00f3n (pozos, r\u00edos, balsas, embalses) y distribuirlos por los campos de <strong><a href=\"https:\/\/naranjasamparo.net\/blog\/que-cantidad-de-fibra-contienen-la-naranja-y-la-mandarina\/\">naranjas<\/a>, <a href=\"https:\/\/naranjasamparo.net\/blog\/beneficios-de-las-mandarinas-baby-para-los-ninos\/\">mandarinas<\/a>, <a href=\"https:\/\/naranjasamparo.net\/blog\/miel-limon-calmar-tos\/\">limones<\/a> <\/strong>,etc. Los arquitectos romanos construyeron los primeros canales eficientes para transporte de agua de unos lugares a otros. Se trataba de obras de gran envergadura que iban a asegurar un sistema de aprovisionamiento de agua. Famoso y conocido por todos es el<a href=\"https:\/\/es.wikipedia.org\/wiki\/Acueducto_de_Segovia\"> <strong>Acueducto de Segovia<\/strong>.<\/a><\/p>\n\n\n\n<p>\u00bfLas acequias para regar las huertos de c\u00edtricos son de origen \u00e1rabe?<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo se gestionan y funcionan  las acequias para regar los c\u00edtricos?<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\"><strong>Las acequias de riego forman redes complejas<\/strong>. Por una parte, tenemos una acequia grande que se llama la acequia madre (s\u00e8quia mare) o mayor que es la que toma el agua del lugar de origen. En segundo lugar, se presentan las acequias hijas o \u201csequioletes\u201d tambi\u00e9n se llaman \u201cfilloles\u201d (hijas) o \u201cramalls\u201d (ramas). Normalmente una red a de acequias tiene un descenso gradual en altitud entre el origen generalmente un rio o manantial y el final del circuito. En muchas ocasiones se tiene que elevar el agua de forma artificial, o bien se utilizan las motobombas para realizar la misma funci\u00f3n.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de Contenidos<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04d97ba46ad\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04d97ba46ad\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/#%C2%BFCon_que_materiales_se_construyen_las_acequias_y_como_se_distribuyen_las_aguas_de_riego\" >\u00bfCon qu\u00e9 materiales se construyen las acequias  y c\u00f3mo se distribuyen las aguas de riego?<\/a><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><ul class='ez-toc-list-level-6' ><li class='ez-toc-heading-level-6'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/#La_forma_de_regar_con_acequias_%E2%80%9Csequies%E2%80%9D_acequias_inundando_el_campo_durante_un_tiempo_controlado_se_denomina_%E2%80%9Cregar_a_manta%E2%80%9D\" >La forma de regar con  acequias \u201cs\u00e9quies\u201d  (acequias) inundando el campo durante un tiempo controlado se denomina \u201cregar a manta.\u201d<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/#%C2%BFEn_que_consiste_el_Riego_por_goteo_%C2%BFQue_sistema_es_mas_eficiente_el_riego_manta_o_el_sistema_de_riego_por_goteo_para_los_citricos\" >\u00bfEn qu\u00e9 consiste el Riego por goteo? \u00bfQu\u00e9 sistema es m\u00e1s eficiente el riego manta o el sistema de riego por goteo para los c\u00edtricos?<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/#En_la_actualidad_la_mayoria_de_las_huertas_valencianas_han_ido_abandonando_el_riego_%E2%80%9Ca_manta%C2%BB_sustituyendolo_por_el_riego_por_goteo_ya_que_se_ahorra_mas_agua_con_este_metodo_incrementando_la_eficiencia_y_sostenibilidad\" >En la actualidad, la mayor\u00eda de las huertas valencianas han ido abandonando el riego \u201ca manta\u00bb sustituy\u00e9ndolo por el riego por goteo, ya que se ahorra m\u00e1s agua con este m\u00e9todo, incrementando la eficiencia y sostenibilidad.<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/#%C2%BFCuales_son_los_objetivos_a_conseguir_en_la_modernizacion_del_regadio_de_citricos_en_la_Comunidad_Valenciana\" >\u00bfCu\u00e1les son los objetivos a conseguir en la modernizaci\u00f3n del regad\u00edo de c\u00edtricos en la Comunidad Valenciana?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/#Cancion_popular_%C2%ABBaix_del_pont_de_cullera%C2%BB_Debajo_del_puente_de_Cullera\" >Canci\u00f3n popular: \u00abBaix del pont de cullera\u00bb (Debajo del puente de Cullera)<\/a><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\" id=\"h-con-que-materiales-se-construyen-las-acequias-y-como-se-distribuyen-las-aguas-de-riego\"><span class=\"ez-toc-section\" id=\"%C2%BFCon_que_materiales_se_construyen_las_acequias_y_como_se_distribuyen_las_aguas_de_riego\"><\/span><strong>\u00bfCon qu\u00e9 materiales se construyen las acequias  y c\u00f3mo se distribuyen las aguas de riego?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Las acequias, generalmente, suelen estar construidas con argamasa, es decir por una mezcla de cal, arena y agua, o bien, con hormig\u00f3n. La distribuci\u00f3n y uso de las aguas corresponde a la Comunidad de regantes de cada acequia. Esta Comunidad destina un horario de riego para cada sector de huertos de <a href=\"http:\/\/naranjasamparo.net\"><strong>naranjas<\/strong><\/a>. En Valencia se resuelven los conflictes entre comunidades de regantes que forman parte de \u00e9l en el famoso <strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Tribunal_de_las_Aguas_de_Valencia\">Tribunal de les A\u00efgues de Val\u00e8ncia<\/a>.<\/strong> <\/p>\n\n\n\n<p>El Tribunal de las Aguas de Valencia es una instituci\u00f3n de Justicia encargada de resolver los conflictos derivados de la utilizaci\u00f3n y aprovechamiento del agua de riego entre los agricultores de las Comunidades de Regantes de las acequias de la Vega de Valencia. Cabe se\u00f1alar que se trata del Tribunal de Justicia m\u00e1s antiguo del mundo.<\/p>\n\n\n\n<p>Los s\u00edndicos o componentes del Tribunal se re\u00fanen cada jueves en la Puerta de los Ap\u00f3stoles de la Catedral de Valencia. El proceso es p\u00fablico, trat\u00e1ndose las problem\u00e1ticas de forma oral y en idioma valenciano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"451\" src=\"https:\/\/naranjasamparo.net\/blog\/wp-content\/uploads\/2022\/09\/Acequias-escalonadas-2.jpeg\" alt=\"acequias escalonadas\" class=\"wp-image-3436\" srcset=\"https:\/\/naranjasamparo.net\/blog\/wp-content\/uploads\/2022\/09\/Acequias-escalonadas-2.jpeg 580w, https:\/\/naranjasamparo.net\/blog\/wp-content\/uploads\/2022\/09\/Acequias-escalonadas-2-416x323.jpeg 416w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><figcaption>Acequias escalonadas<\/figcaption><\/figure>\n\n\n\n<p><strong>\u00bfQu\u00e9 es el Sistema de riego a manta?<\/strong><\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-la-forma-de-regar-con-acequias-sequies-acequias-inundando-el-campo-durante-un-tiempo-controlado-se-denomina-regar-a-manta\"><span class=\"ez-toc-section\" id=\"La_forma_de_regar_con_acequias_%E2%80%9Csequies%E2%80%9D_acequias_inundando_el_campo_durante_un_tiempo_controlado_se_denomina_%E2%80%9Cregar_a_manta%E2%80%9D\"><\/span>La forma de regar con  acequias \u201cs\u00e9quies\u201d  (acequias) inundando el campo durante un tiempo controlado se denomina \u201cregar a manta.\u201d<span class=\"ez-toc-section-end\"><\/span><\/h6>\n\n\n\n<p class=\"has-text-align-left\"><strong>El riego a manta es el riego por inundaci\u00f3n del terreno.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left\">La manera de regar a manta es la siguiente. Se prepara el huerto o bancal separando con \u201cc\u00e8rcols y cavallons\u201d -lomos de tierra que separan las distintas calles o zonas por las que se va a regar. Una vez se llena la \u201csequioleta\u201d de agua se abre la\u201d paleta\u201d -tambi\u00e9n llamado port\u00f3n o trastellador- que es una peque\u00f1a compuerta de cada parte del bancal. A medida que llega el agua al final de la calle o zona delimitada por los \u201ccavallones\u201d, se vuelve a taponar la peque\u00f1a compuerta y se abre la siguiente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-en-que-consiste-el-riego-por-goteo-que-sistema-es-mas-eficiente-el-riego-manta-o-el-sistema-de-riego-por-goteo-para-los-citricos\"><span class=\"ez-toc-section\" id=\"%C2%BFEn_que_consiste_el_Riego_por_goteo_%C2%BFQue_sistema_es_mas_eficiente_el_riego_manta_o_el_sistema_de_riego_por_goteo_para_los_citricos\"><\/span><strong>\u00bfEn qu\u00e9 consiste el Riego por goteo? \u00bfQu\u00e9 sistema es m\u00e1s eficiente el riego manta o el sistema de riego por goteo para los c\u00edtricos?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En el <strong>riego por goteo se permite conducir el agua mediante una red de tuber\u00edas<\/strong> que se aplican a los cultivos a trav\u00e9s del gota a gota mediante unos goteros que recorren todo el bancal por debajo de los naranjos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-en-la-actualidad-la-mayoria-de-las-huertas-valencianas-han-ido-abandonando-el-riego-a-manta-sustituyendolo-por-el-riego-por-goteo-ya-que-se-ahorra-mas-agua-con-este-metodo-incrementando-la-eficiencia-y-sostenibilidad\"><span class=\"ez-toc-section\" id=\"En_la_actualidad_la_mayoria_de_las_huertas_valencianas_han_ido_abandonando_el_riego_%E2%80%9Ca_manta%C2%BB_sustituyendolo_por_el_riego_por_goteo_ya_que_se_ahorra_mas_agua_con_este_metodo_incrementando_la_eficiencia_y_sostenibilidad\"><\/span>En la actualidad, la mayor\u00eda de las huertas valencianas han ido abandonando el riego \u201ca manta\u00bb sustituy\u00e9ndolo por el <strong>riego por goteo<\/strong>, ya que se ahorra m\u00e1s agua con este m\u00e9todo, incrementando la eficiencia y sostenibilidad.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_los_objetivos_a_conseguir_en_la_modernizacion_del_regadio_de_citricos_en_la_Comunidad_Valenciana\"><\/span><strong>\u00bfCu\u00e1les son los objetivos a conseguir en la modernizaci\u00f3n del regad\u00edo de c\u00edtricos en la Comunidad Valenciana?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Entre los principales objetivos de la modernizaci\u00f3n del regad\u00edo de la comunidad valenciana se pretende:<\/p>\n\n\n\n<p>&#8211; La optimizaci\u00f3n y modernizaci\u00f3n en el uso de los recursos para el riego<br>&#8211; Fomento del ahorro del agua, incrementando su eficiencia y sostenibilidad<br>&#8211; Recuperaci\u00f3n de los acu\u00edferos tanto en cantidad como en calidad de las aguas<\/p>\n\n\n\n<p>Para terminar, presentamos una canci\u00f3n<strong> tradicional valenciana \u201cBaix del pont de Cullera\u201d <\/strong>en donde se alude al t\u00edtulo de este art\u00edculo: \u201csequioleta\u201d, canci\u00f3n por cierto muy cantada y conocida por los ni\u00f1os y ni\u00f1as de la Comunidad Valenciana:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cancion_popular_%C2%ABBaix_del_pont_de_cullera%C2%BB_Debajo_del_puente_de_Cullera\"><\/span>Canci\u00f3n popular: \u00ab<strong>Baix del pont de cullera<\/strong>\u00bb (Debajo del puente de Cullera)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p class=\"has-text-align-left\">Baix del pont de Cullera ler\u00e9 ler\u00e9<br>ballava un &#8216;sapo&#8217; ler\u00e9<br>ballava un &#8216;sapo&#8217; ler\u00e9<br>Sembla un tap\u00f3 de bassa ler\u00e9 ler\u00e9<br>fent-se el &#8216;beato&#8217; ler\u00e9,<br>fent-se el &#8216;beato&#8217;.<\/p>\n\n\n\n<p class=\"has-text-align-left\">All\u00e0 baix la <strong>sequioleta<\/strong><br>ballava un pato ler\u00e9 ler\u00e9<br>mec mec mec<br>i quines volteretes<br>donava el nano ler\u00e9 ler\u00e9<br>mec mec mec<\/p>\n\n\n\n<p class=\"has-text-align-left\"><strong>Traducci\u00f3n:<\/strong><p class=\"has-text-align-left\">Debajo del puente de Cullera ler\u00e9 ler\u00e9<br>bailaba un &#8216;sapo&#8217; ler\u00e9<br>bailaba un &#8216;sapo&#8217; ler\u00e9<br>Parece un tap\u00f3n de balsa ler\u00e9 ler\u00e9<br>haci\u00e9ndose el &#8216;beato&#8217; ler\u00e9,<br>haci\u00e9ndose el &#8216;beato&#8217;.<\/p>   <p class=\"has-text-align-left\">All\u00ed bajo la acequia<br>bailaba un pato ler\u00e9 ler\u00e9<br>mec mec mec<br>i qu\u00e9 volteretas<br>daba el peque\u00f1ajo ler\u00e9 ler\u00e9<br>mec mec mec<\/p> <\/p>\n\n\n\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/naranjasamparo.net\/blog\/wp-content\/uploads\/2022\/06\/video-acequia-1.mp4\"><\/video><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfCu\u00e1l es el origen del regad\u00edo de los c\u00edtricos de los campos valencianos? Las acequias, han constituido durante muchos a\u00f1os un papel fundamental en el regad\u00edo de los c\u00edtricos. Las acequias son canales o conductos por donde se conducen las aguas para regar campos de cultivo, como pueden ser los campos de c\u00edtricos.Estas obras son &#8230; <a title=\"Regad\u00edo de los c\u00edtricos: Sistemas\" class=\"read-more\" href=\"https:\/\/naranjasamparo.net\/blog\/regadio-de-los-citricos-sistemas\/\" aria-label=\"Leer m\u00e1s sobre Regad\u00edo de los c\u00edtricos: Sistemas\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":3440,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1628],"tags":[1699,1667,60,70,1560,1698,1696,1697],"class_list":["post-3367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-ahorroagua","tag-alimentos-de-proximidad","tag-citricos","tag-naranjas-amparo","tag-naranjas-valencianas","tag-recursos-hidraulicos","tag-regadio","tag-sostenibilidad"],"_links":{"self":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts\/3367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/comments?post=3367"}],"version-history":[{"count":31,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts\/3367\/revisions"}],"predecessor-version":[{"id":3449,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts\/3367\/revisions\/3449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/media\/3440"}],"wp:attachment":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/media?parent=3367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/categories?post=3367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/tags?post=3367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}