{"id":3148,"date":"2022-01-20T09:08:00","date_gmt":"2022-01-20T08:08:00","guid":{"rendered":"https:\/\/naranjasamparo.net\/blog\/?p=3148"},"modified":"2024-02-20T20:24:22","modified_gmt":"2024-02-20T19:24:22","slug":"que-representan-las-naranjas-en-las-tres-peliculas-de-el-padrino","status":"publish","type":"post","link":"https:\/\/naranjasamparo.net\/blog\/que-representan-las-naranjas-en-las-tres-peliculas-de-el-padrino\/","title":{"rendered":"Qu\u00e9 representan las naranjas en las tres pel\u00edculas de \u201cEl padrino\u201d"},"content":{"rendered":"<p>La trilog\u00eda de \u201cEl Padrino\u201d, pel\u00edculas dirigidas por Francis Ford Coppola aparecen en diferentes escenas\u00a0<strong>naranjas\u00a0<\/strong>casi siempre seguidas de una muerte de alg\u00fan personaje relevante.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/i.blogs.es\/02554d\/oscarfrancis\/1366_2000.jpg\" alt=\"Oscar Isaac ser\u00e1 Francis Ford Coppola en &amp;#39;Francis and The Godfather&amp;#39;, la  pel\u00edcula que explorar\u00e1 el rodaje de &amp;#39;El Padrino\" \/><\/p>\n<p style=\"text-align: center;\">Figura: Francis Ford Coppola \u00a8Fuente spinoff.com\u00a8<\/p>\n<p>\u00bfSe usaron las naranjas como s\u00edmbolo por parte del Director o guionistas? \u00bfQu\u00e9 significaron?<\/p>\n<p>Esta relaci\u00f3n entre la imagen de naranjas seguidas por un evento que implica una muerte o una tragedia inminente, lleva a pensar en el uso de la naranja como s\u00edmbolo por parte del director o de los guionistas de esta importante trilog\u00eda.<br \/>\nLas pel\u00edculas que est\u00e1n basadas en el libro The Godfather de Mario Puzo, constituyen una de las mejores trilog\u00edas sobre la mafia en la historia del cine.<\/p>\n<p>Aunque no somos expertos en an\u00e1lisis del cine, podemos deleitarnos con estas pel\u00edculas que, seg\u00fan la opini\u00f3n de los cr\u00edticos y especialistas en cine, vale la pena volverlas a ver incluso varias veces para apreciar tanto la interpretaci\u00f3n, el argumento, la m\u00fasica, la fotograf\u00eda etc. Y tambi\u00e9n detalles para estar alerta como cuando aparecen una o varias naranjas que nos avisan de que alguna fatalidad est\u00e1 a punto de ocurrir.<\/p>\n<p>Vamos a detenernos en algunas de estas escenas en las que de forma global se predica la uni\u00f3n y la importancia entre los miembros de la familia, etc, Pero, en realidad se manejan no solo las tradiciones familiares. Hay deudas que saldar, venganzas, traiciones\u2026y naranjas que se muestran en medio de escenas oscuras y que presagian que algo malo va a suceder.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de Contenidos<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04ed5fb0ec0\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04ed5fb0ec0\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/naranjasamparo.net\/blog\/que-representan-las-naranjas-en-las-tres-peliculas-de-el-padrino\/#%C2%A1Hay_que_estar_atento_y_no_perderselas\" >\u00a1Hay que estar atento y no perd\u00e9rselas!<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/naranjasamparo.net\/blog\/que-representan-las-naranjas-en-las-tres-peliculas-de-el-padrino\/#Por_ultimo_simbolos_aparte_en_sabor_y_estetica_tanto_en_peliculas_como_en_la_vida_misma_la_naranja_siempre_combina_estupendamente_En_zumo_natural_en_bizcochos_o_como_acompanamiento_en_distintos_platos\" >Por \u00faltimo, s\u00edmbolos aparte, en sabor y est\u00e9tica tanto en pel\u00edculas como en la vida misma, la naranja siempre combina estupendamente: En zumo,\u00a0 natural, en bizcochos o como acompa\u00f1amiento en distintos platos.<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"%C2%A1Hay_que_estar_atento_y_no_perderselas\"><\/span>\u00a1Hay que estar atento y no perd\u00e9rselas!<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"padding-left: 40px;\">1.-La primera vez aparecen cuando Vito Corleone, est\u00e1 comprando <strong>naranjas <\/strong>en un mercado es entonces cuando le disparan. Don Vito cae abatido en la calle y se observa como las naranjas quedan esparcidas por la calle.<\/p>\n<p style=\"padding-left: 40px;\">2.-Una de las escenas m\u00e1s impactantes resulta ser la que aparece la cabeza del caballo muerto por orden de Don Vito. Ello debido a que el propietario del caballo no se avino a una propuesta de Vito Corleone en la cena del d\u00eda anterior, en cuya mesa se mostraba una fuente con naranjas.<\/p>\n<p style=\"padding-left: 40px;\">3.- Antes de ser atacado, Sonny, el hijo de Don Vito Corleone, pasa con el coche por un lugar donde aparece un cartel que anuncia la venta de naranjas.<\/p>\n<p style=\"padding-left: 40px;\">4.- En una reuni\u00f3n donde aparecen sentados frente a una mesa los capos de la Mafia, se muestra un bol con naranjas\u2026en las escenas siguientes son asesinados.<\/p>\n<p style=\"padding-left: 40px;\">5.-Antes de morir, Don Vito juega con su nieto, mientras se pone en los dientes unos recortes de<strong><a href=\"https:\/\/naranjasamparo.net\/blog\/manualidades-de-navidad-con-cascaras-de-mandarina\/\"> piel de naranja<\/a>.<\/strong><\/p>\n<p style=\"padding-left: 40px;\">6.- Don Fannucci, juega con una naranja en su mano justo antes de ser asesinado.<\/p>\n<p style=\"padding-left: 40px;\">7.- Johny Ola le ofrece a Michael una naranja de Miami. Poco despu\u00e9s es asesinado.<\/p>\n<p style=\"padding-left: 40px;\">8.- En la boda de Connie, hija de Don Vito, se muestra a Sal agarrando una naranja. M\u00e1s tarde, Sal traicion\u00f3 a la familia y Michael Corleone hizo que lo mataran.<\/p>\n<p style=\"padding-left: 40px;\">9.- En una secuencia aparece Tessio con una naranja en sus manos. \u00c9ste traicion\u00f3 a la familia Corleone.<\/p>\n<p style=\"padding-left: 40px;\">10.- Michael est\u00e1 comiendo una naranja en su encuentro con Tom Hagen y Rocco Lampone, mientras planean el asesinato de Hyman Roth, quien es asesinado.<\/p>\n<p style=\"padding-left: 40px;\">11.-Al final de la tercera parte Michael Corleone con una naranja en la mano, muere y la naranja al caer sale rodando.<\/p>\n<p>Hay que tener en cuenta que <strong>en Sicilia se producen y se consumen naranja<\/strong>s y en la pel\u00edcula la mayor\u00eda de los personajes son de origen siciliano. Por otra parte, los lugares en que se rod\u00f3 la pel\u00edcula son productores de naranjas: California y Florida.<\/p>\n<p>En entrevista al mism\u00edsimo Coppola, sobre la intencionalidad de atribuir a la naranja el s\u00edmbolo de la muerte, asegur\u00f3 que en principio se utilizaron para dar una nota de color ya que en las pel\u00edculas predominan temas con escenas sombr\u00edas, en sitios cerrados, los trajes oscuros, etc<\/p>\n<p>La verdad es que el contraste que ofrece el<strong> color alegre y brillante de la naranja se agradece<\/strong> frente a las escenas oscuras, ambientes de muertes, venganzas y traiciones.<\/p>\n<p>Os recomendamos volver a ver la trilog\u00eda de El Padrino y estar atento a los detalles en los que aparecen naranjas para comprobar por nosotros mismos la simbolog\u00eda entre naranja y fatalidad.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Por_ultimo_simbolos_aparte_en_sabor_y_estetica_tanto_en_peliculas_como_en_la_vida_misma_la_naranja_siempre_combina_estupendamente_En_zumo_natural_en_bizcochos_o_como_acompanamiento_en_distintos_platos\"><\/span>Por \u00faltimo, s\u00edmbolos aparte, en sabor y est\u00e9tica<strong> tanto en pel\u00edculas como en la vida misma, la naranja siempre combina estupendamente: En zumo,\u00a0 natural, en bizcochos o como acompa\u00f1amiento en distintos platos. <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Sigue las recetas de nuestro blog y lo comprobar\u00e1s.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La trilog\u00eda de \u201cEl Padrino\u201d, pel\u00edculas dirigidas por Francis Ford Coppola aparecen en diferentes escenas\u00a0naranjas\u00a0casi siempre seguidas de una muerte de alg\u00fan personaje relevante. Figura: Francis Ford Coppola \u00a8Fuente spinoff.com\u00a8 \u00bfSe usaron las naranjas como s\u00edmbolo por parte del Director o guionistas? \u00bfQu\u00e9 significaron? Esta relaci\u00f3n entre la imagen de naranjas seguidas por un evento &#8230; <a title=\"Qu\u00e9 representan las naranjas en las tres pel\u00edculas de \u201cEl padrino\u201d\" class=\"read-more\" href=\"https:\/\/naranjasamparo.net\/blog\/que-representan-las-naranjas-en-las-tres-peliculas-de-el-padrino\/\" aria-label=\"Leer m\u00e1s sobre Qu\u00e9 representan las naranjas en las tres pel\u00edculas de \u201cEl padrino\u201d\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1628],"tags":[1676,1652,70,1675,1560,1677],"class_list":["post-3148","post","type-post","status-publish","format-standard","hentry","category-cultura","tag-alimentacion-y-ocio","tag-alimentos-naturales","tag-naranjas-amparo","tag-naranjas-en-el-cine","tag-naranjas-valencianas","tag-naranjas-y-diabetes"],"_links":{"self":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts\/3148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/comments?post=3148"}],"version-history":[{"count":8,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts\/3148\/revisions"}],"predecessor-version":[{"id":4018,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/posts\/3148\/revisions\/4018"}],"wp:attachment":[{"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/media?parent=3148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/categories?post=3148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/naranjasamparo.net\/blog\/wp-json\/wp\/v2\/tags?post=3148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}